{"id":2228,"date":"2020-12-21T13:07:17","date_gmt":"2020-12-21T13:07:17","guid":{"rendered":"https:\/\/www.steinbeis-mediation.com\/?page_id=2228"},"modified":"2021-12-20T14:47:31","modified_gmt":"2021-12-20T14:47:31","slug":"die-mediation-the-trade-magazine","status":"publish","type":"page","link":"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/en\/resources\/die-mediation-the-trade-magazine\/","title":{"rendered":"&#8220;Die Mediation&#8221; &#8211; the trade magazine"},"content":{"rendered":"<div class=\"vce-row-container\"><div class=\"vce-row vce-row--col-gap-30 form-common-main vce-row-content--top\" data-vce-full-width=\"true\" data-vce-stretch-content=\"true\" id=\"el-d8fb318d\" data-vce-do-apply=\"all el-d8fb318d\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-d0837e4f\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-d0837e4f\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-d0837e4f\"><div class=\"vce-single-image-container vce-single-image--align-left\"><div class=\"vce vce-single-image-wrapper\" id=\"el-906b80b7\" data-vce-do-apply=\"all el-906b80b7\"><figure><div class=\"vce-single-image-inner vce-single-image--absolute\"><img loading=\"lazy\" decoding=\"async\" class=\"vce-single-image vcv-lozad\" data-src=\"https:\/\/projects.theglobalwebdev.com:8191\/steinbeis\/wp-content\/uploads\/2020\/10\/banner-img-2.jpg\" width=\"0\" height=\"0\" src=\"\" data-img-src=\"http:\/\/projects.theglobalwebdev.com:8191\/steinbeis\/wp-content\/uploads\/2020\/10\/banner-img-2.jpg\" alt=\"\" title=\"banner-img-2\" \/><noscript>\n        <img loading=\"lazy\" decoding=\"async\" class=\"vce-single-image\" src=\"http:\/\/projects.theglobalwebdev.com:8191\/steinbeis\/wp-content\/uploads\/2020\/10\/banner-img-2.jpg\" width=\"0\" height=\"0\" alt=\"\" title=\"banner-img-2\" \/>\n      <\/noscript><\/div><figcaption hidden=\"\"><\/figcaption><\/figure><\/div><\/div><div class=\"vce-raw-html\"><div class=\"vce-raw-html-wrapper\" id=\"el-7302ba51\" data-vce-do-apply=\"all el-7302ba51\"><div class=\"comman-title-main-wrap\"><h3 class=\"comman-title\"><strong>'Die Mediation'<\/strong><\/h3><p class=\"comman-subtitle\">In our quarterly magazine, we deal with mediation and much more.\n<\/p><\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 die-mediation-text-block vce-row-content--top\" id=\"el-4afd9119\" data-vce-do-apply=\"all el-4afd9119\"><div class=\"vce-content-background-container\"><\/div><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-afa8c157\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-afa8c157\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-afa8c157\"><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-7a609a9e\" data-vce-do-apply=\"all el-7a609a9e\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-row-container\"><div class=\"vce-row vce-row--col-gap-30 magazine-grid-list-wrap vce-row-content--top\" data-vce-full-width=\"true\" id=\"el-9030ffbf\" data-vce-do-apply=\"all el-9030ffbf\"><div class=\"vce-content-background-container\"><\/div><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-9a99df13\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-9a99df13\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-9a99df13\"><div class=\"vce-single-image-container vce-single-image--align-center\"><div class=\"vce vce-single-image-wrapper\" id=\"el-79a96f45\" data-vce-do-apply=\"all el-79a96f45\"><figure><a href=\"http:\/\/www.die-mediation.de\/bestellen\" title=\"Die Mediation\" target=\"_blank\" class=\"vce-single-image-inner vce-single-image--absolute\" style=\"padding-bottom: 141.5%; width: 200px;\" rel=\"noopener\"><img decoding=\"async\" class=\"vce-single-image\" src=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2020\/11\/Pictureb.png\" data-img-src=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2020\/11\/Pictureb.png\" alt=\"\" title=\"Pictureb\"><\/a><figcaption hidden=\"\"><\/figcaption><\/figure><\/div><\/div><\/div><\/div><\/div><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first\" id=\"el-6161f7c1\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-6161f7c1\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-6161f7c1\"><div class=\"vce-single-image-container vce-single-image--align-center\"><div class=\"vce vce-single-image-wrapper\" id=\"el-a370e338\" data-vce-do-apply=\"all el-a370e338\"><figure><a href=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2021\/12\/216612-Edition-I-2021-ePaper_MedRES.pdf\" title=\"Die Mediation\" target=\"_blank\" class=\"vce-single-image-inner vce-single-image--absolute\" style=\"padding-bottom: 141.436%; width: 1810px;\" rel=\"noopener\"><img decoding=\"async\" class=\"vce-single-image\" src=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2021\/12\/216612-Edition-I-2021-ePaper_Cover-scaled.jpg\" data-img-src=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2021\/12\/216612-Edition-I-2021-ePaper_Cover-scaled.jpg\" alt=\"Die Mediation bild von steinbeis\" title=\"\"><\/a><figcaption hidden=\"\"><\/figcaption><\/figure><\/div><\/div><\/div><\/div><\/div><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last\" id=\"el-f99c74be\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-f99c74be\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-f99c74be\"><div class=\"vce-single-image-container vce-single-image--align-center\"><div class=\"vce vce-single-image-wrapper\" id=\"el-e4e0984f\" data-vce-do-apply=\"all el-e4e0984f\"><figure><a href=\"http:\/\/www.die-mediation.de\/bestellen\" title=\"Die Mediation\" target=\"_blank\" class=\"vce-single-image-inner vce-single-image--absolute\" style=\"padding-bottom: 141.5%; width: 200px;\" rel=\"noopener\"><img decoding=\"async\" class=\"vce-single-image\" src=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2020\/11\/cover-img-3.jpg\" data-img-src=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2020\/11\/cover-img-3.jpg\" alt=\"\" title=\"Die Mediation\"><\/a><figcaption hidden=\"\"><\/figcaption><\/figure><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-row-container\"><div class=\"vce-row vce-row--col-gap-30 magazine-grid-list-wrap corporate-success-second-section vce-row-content--top\" data-vce-full-width=\"true\" id=\"el-31896552\" data-vce-do-apply=\"all el-31896552\"><div class=\"vce-content-background-container\"><\/div><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-3e31bc0a\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-3e31bc0a\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-3e31bc0a\"><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-df790443\" data-vce-do-apply=\"all el-df790443\"><p>Discover new topics full of in-depth and multi-faceted articles by experts in mediation, law and social sciences. Read about the latest trends in recurring topics such as conflict resoltuion, change management, leadership, best market practices, and cross-cultural travel. <\/p><\/div><\/div><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-3c2a7649\" data-vce-do-apply=\"all el-3c2a7649\"><p style=\"text-align: center;\">Buy your German copy and subscribe to the magazine, or explore our premium books <strong><a href=\"https:\/\/www.die-mediation.de\/\"><span style=\"color: #008080;\">here!<\/span><\/a><\/strong><\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-row-container\"><div class=\"vce-row vce-element--has-background vce-row--col-gap-30 corporate-success-second-section vce-row-content--top\" data-vce-full-width=\"true\" id=\"el-0b7e4bcc\" data-vce-do-apply=\"all el-0b7e4bcc\"><div class=\"vce-content-background-container\"><\/div><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-58190bb9\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-58190bb9\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-58190bb9\"><div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 code-app-wrap vce-row-content--top\" id=\"el-9686b92c\" data-vce-do-apply=\"all el-9686b92c\"><div class=\"vce-content-background-container\"><\/div><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-f8258ada\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-f8258ada\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-f8258ada\"><div class=\"vce-single-image-container vce-single-image--align-center\"><div class=\"vce vce-single-image-wrapper\" id=\"el-3e404108\" data-vce-do-apply=\"all el-3e404108\"><figure><div class=\"vce-single-image-inner vce-single-image--absolute\" style=\"padding-bottom: 100%; width: 181px;\"><img loading=\"lazy\" decoding=\"async\" class=\"vce-single-image vcv-lozad\" data-src=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2021\/12\/QR-Code-181x181.png\" width=\"181\" height=\"181\" srcset=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2021\/12\/QR-Code-181x181.png 181w\" src=\"\" data-img-src=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2020\/12\/QR-Code.png\" alt=\"Bild von Steinbeis-mediation.com Die Mediation\" title=\"QR Code\" \/><noscript>\n        <img loading=\"lazy\" decoding=\"async\" class=\"vce-single-image\" src=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2020\/12\/QR-Code.png\" width=\"181\" height=\"181\" alt=\"Bild von Steinbeis-mediation.com Die Mediation\" title=\"QR Code\" \/>\n      <\/noscript><\/div><figcaption hidden=\"\"><\/figcaption><\/figure><\/div><\/div><div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 code-app-inner-wrap vce-row-content--top\" id=\"el-7c071583\" data-vce-do-apply=\"all el-7c071583\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-afd913bd\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-afd913bd\"><div class=\"vce-content-background-container\"><\/div><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-afd913bd\"><div class=\"vce-single-image-container vce-single-image--align-right\"><div class=\"vce vce-single-image-wrapper\" id=\"el-77f13556\" data-vce-do-apply=\"all el-77f13556\"><figure><div class=\"vce-single-image-inner vce-single-image--absolute\" style=\"padding-bottom: 29.6296%; width: 189px;\"><img loading=\"lazy\" decoding=\"async\" class=\"vce-single-image vcv-lozad\" data-src=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2021\/12\/Google-Play-189x56.png\" width=\"189\" height=\"56\" srcset=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2021\/12\/Google-Play-189x56.png 189w\" src=\"\" data-img-src=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2020\/12\/Google-Play.png\" alt=\"\" title=\"Google-Play\" \/><noscript>\n        <img loading=\"lazy\" decoding=\"async\" class=\"vce-single-image\" src=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2020\/12\/Google-Play.png\" width=\"189\" height=\"56\" alt=\"\" title=\"Google-Play\" \/>\n      <\/noscript><\/div><figcaption hidden=\"\"><\/figcaption><\/figure><\/div><\/div><\/div><\/div><\/div><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last\" id=\"el-5987b379\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-5987b379\"><div class=\"vce-content-background-container\"><\/div><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-5987b379\"><div class=\"vce-single-image-container vce-single-image--align-left\"><div class=\"vce vce-single-image-wrapper\" id=\"el-d93ca2a8\" data-vce-do-apply=\"all el-d93ca2a8\"><figure><div class=\"vce-single-image-inner vce-single-image--absolute\" style=\"padding-bottom: 29.6296%; width: 189px;\"><img loading=\"lazy\" decoding=\"async\" class=\"vce-single-image vcv-lozad\" data-src=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2021\/12\/Image-189x56.png\" width=\"189\" height=\"56\" srcset=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2021\/12\/Image-189x56.png 189w\" src=\"\" data-img-src=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2020\/12\/Image.png\" alt=\"\" title=\"Image\" \/><noscript>\n        <img loading=\"lazy\" decoding=\"async\" class=\"vce-single-image\" src=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2020\/12\/Image.png\" width=\"189\" height=\"56\" alt=\"\" title=\"Image\" \/>\n      <\/noscript><\/div><figcaption hidden=\"\"><\/figcaption><\/figure><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last\" id=\"el-7c8acdf4\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-7c8acdf4\"><div class=\"vce-content-background-container\"><\/div><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-7c8acdf4\"><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-0b1a6a54\" data-vce-do-apply=\"all el-0b1a6a54\"><h3 style=\"text-align: left;\"><span style=\"font-size: 14pt;\"><strong><span style=\"font-weight: 400; font-style: normal;\">Now also as<\/span> App!<\/strong><\/span><\/h3><\/div><\/div><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-7569b08b\" data-vce-do-apply=\"all el-7569b08b\"><p style=\"text-align: left; line-height: 1.25;\"><span style=\"font-size: 12pt;\">Our German magazine app offers a multimedia experience for your continuing education in conflict resolution. This gives you access to our wide range of mediation topics, anytime, anywhere. The app has a full text search in all archive editions so you can easily search for and research your main areas of interest.<\/span><\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-5f32956e\" data-vce-do-apply=\"all el-5f32956e\"><p style=\"text-align: left;\">Download it now from the Apple App Store or Google Play Store.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-row-container\"><div class=\"vce-row vce-row--col-gap-30 our-trade-journal-main-wrap cross-one-many-advantage vce-row-equal-height vce-row-content--middle\" data-vce-full-width=\"true\" id=\"el-b39a3006\" data-vce-do-apply=\"all el-b39a3006\"><div class=\"vce-content-background-container\"><\/div><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-60p vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-first vce-col--lg-first vce-col--xl-first our-trade-first-column\" id=\"el-12ee52b0\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-12ee52b0\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-12ee52b0\"><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-bfa97807\" data-vce-do-apply=\"all el-bfa97807\"><p><span style=\"font-weight: 400; font-style: normal; color: #2e849b; font-size: 16pt;\">Your advantages-<\/span><\/p><\/div><\/div><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-ee1dfec9\" data-vce-do-apply=\"all el-ee1dfec9\"><ul>\n \t<li>All issues are available online at any time<\/li>\n \t<li>Journal archive with full text search for premium subscribers<\/li>\n \t<li>Can also be linked to a print subscription<\/li>\n \t<li>Free online edition of our Q1 2020 magazine<\/li>\n<\/ul><\/div><\/div><\/div><\/div><\/div><div class=\"vce-col vce-col--md-40p vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last our-trade-first-column\" id=\"el-8d5aeed9\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-8d5aeed9\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-8d5aeed9\"><div class=\"vce-single-image-container vce-single-image--align-left\"><div class=\"vce vce-single-image-wrapper\" id=\"el-4f7ba35a\" data-vce-do-apply=\"all el-4f7ba35a\"><figure><a href=\"http:\/\/www.die-mediation.de\/bestellen\" title=\"\" target=\"_blank\" class=\"vce-single-image-inner vce-single-image--absolute\" style=\"padding-bottom: 141.776%; width: 304px;\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"vce-single-image vcv-lozad\" data-src=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2021\/12\/magazine-1-304x431.jpg\" width=\"304\" height=\"431\" srcset=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2021\/12\/magazine-1-304x431.jpg 304w\" src=\"\" data-img-src=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2020\/12\/magazine-1.jpg\" alt=\"\" title=\"magazine\" \/><noscript>\n        <img loading=\"lazy\" decoding=\"async\" class=\"vce-single-image\" src=\"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2020\/12\/magazine-1.jpg\" width=\"304\" height=\"431\" alt=\"\" title=\"magazine\" \/>\n      <\/noscript><\/a><figcaption hidden=\"\"><\/figcaption><\/figure><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-content--top\" id=\"el-3e5984ec\" data-vce-do-apply=\"all el-3e5984ec\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-f5d5ace7\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-f5d5ace7\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-f5d5ace7\"><div class=\"vce-global-element vce\" id=\"el-17a1158c\" data-vce-do-apply=\"all el-17a1158c\"><div class=\"vce-global-template-inner\"><link rel='stylesheet' id='wpml-blocks-css' href='https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/plugins\/sitepress-multilingual-cms\/dist\/css\/blocks\/styles.css?ver=4.6.10' media='all' \/>\n<link rel='stylesheet' id='contact-form-7-css' href='https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/plugins\/contact-form-7\/includes\/css\/styles.css?ver=5.9.4' media='all' \/>\n<link rel='stylesheet' id='daepl-css' href='https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/plugins\/dae-plus\/css\/dae.css?ver=1715188715' media='all' \/>\n<link rel='stylesheet' id='dae-download-css' href='https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/plugins\/download-after-email\/css\/download.css?ver=1715590211' media='all' \/>\n<link rel='stylesheet' id='dashicons-css' href='https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-includes\/css\/dashicons.min.css?ver=6.5.3' media='all' \/>\n<link rel='stylesheet' id='dae-fa-css' href='https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/plugins\/download-after-email\/css\/all.css?ver=6.5.3' media='all' \/>\n<link rel='stylesheet' id='dsgvoyoutube-style-css' href='https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/plugins\/dsgvo-youtube\/css\/style.php?ver=6.5.3' media='all' \/>\n<link rel='stylesheet' id='cdsgvogdpryoutube-css' href='https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/plugins\/dsgvo-youtube\/includes\/..\/css\/jquery.fancybox.min.css?ver=6.5.3' media='all' \/>\n<link rel='stylesheet' id='wpa-css-css' href='https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/plugins\/honeypot\/includes\/css\/wpa.css?ver=2.1.20' media='all' \/>\n<link rel='stylesheet' id='wpml-legacy-horizontal-list-0-css' href='https:\/\/www.steinbeis-mediation.com\/wp-content\/plugins\/sitepress-multilingual-cms\/templates\/language-switchers\/legacy-list-horizontal\/style.min.css?ver=1' media='all' \/>\n<link rel='stylesheet' id='uacf7-frontend-style-css' href='https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/plugins\/ultimate-addons-for-contact-form-7\/assets\/css\/uacf7-frontend.css?ver=6.5.3' media='all' \/>\n<link rel='stylesheet' id='uacf7-fontawesome-4-css' href='https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/plugins\/ultimate-addons-for-contact-form-7\/assets\/admin\/libs\/font-awesome\/fontawesome4\/css\/font-awesome.min.css?ver=1.0.0' media='all' \/>\n<link rel='stylesheet' id='uacf7-fontawesome-5-css' href='https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/plugins\/ultimate-addons-for-contact-form-7\/assets\/admin\/libs\/font-awesome\/fontawesome5\/css\/all.min.css?ver=1.0.0' media='all' \/>\n<link rel='stylesheet' id='uacf7-fontawesome-6-css' href='https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/plugins\/ultimate-addons-for-contact-form-7\/assets\/admin\/libs\/font-awesome\/fontawesome6\/css\/all.min.css?ver=1.0.0' media='all' \/>\n<link rel='stylesheet' id='uacf7-remixicon-css' href='https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/plugins\/ultimate-addons-for-contact-form-7\/assets\/admin\/libs\/remixicon\/remixicon.css?ver=1.0.0' media='all' \/>\n<link rel='stylesheet' id='cmplz-general-css' href='https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/plugins\/complianz-gdpr\/assets\/css\/cookieblocker.min.css?ver=1715190365' media='all' \/>\n<link rel='stylesheet' id='wpweb-style-css' href='https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/themes\/wpweb\/style.css?ver=1.0.0' media='all' \/>\n<style id='wpweb-style-inline-css'>\n.color-accent,.color-accent-hover:hover,.color-accent-hover:focus,:root .has-accent-color,.has-drop-cap:not(:focus):first-letter,.wp-block-button.is-style-outline,a { color: #cd2653; }blockquote,.border-color-accent,.border-color-accent-hover:hover,.border-color-accent-hover:focus { border-color: #cd2653; }button,.button,.faux-button,.wp-block-button__link,.wp-block-file .wp-block-file__button,input[type=\"button\"],input[type=\"reset\"],input[type=\"submit\"],.bg-accent,.bg-accent-hover:hover,.bg-accent-hover:focus,:root .has-accent-background-color,.comment-reply-link { background-color: #cd2653; }.fill-children-accent,.fill-children-accent * { fill: #cd2653; }body,.entry-title a,:root .has-primary-color { color: #000000; }:root .has-primary-background-color { background-color: #000000; }cite,figcaption,.wp-caption-text,.post-meta,.entry-content .wp-block-archives li,.entry-content .wp-block-categories li,.entry-content .wp-block-latest-posts li,.wp-block-latest-comments__comment-date,.wp-block-latest-posts__post-date,.wp-block-embed figcaption,.wp-block-image figcaption,.wp-block-pullquote cite,.comment-metadata,.comment-respond .comment-notes,.comment-respond .logged-in-as,.pagination .dots,.entry-content hr:not(.has-background),hr.styled-separator,:root .has-secondary-color { color: #6d6d6d; }:root .has-secondary-background-color { background-color: #6d6d6d; }pre,fieldset,input,textarea,table,table *,hr { border-color: #dcd7ca; }caption,code,code,kbd,samp,.wp-block-table.is-style-stripes tbody tr:nth-child(odd),:root .has-subtle-background-background-color { background-color: #dcd7ca; }.wp-block-table.is-style-stripes { border-bottom-color: #dcd7ca; }.wp-block-latest-posts.is-grid li { border-top-color: #dcd7ca; }:root .has-subtle-background-color { color: #dcd7ca; }body:not(.overlay-header) .primary-menu > li > a,body:not(.overlay-header) .primary-menu > li > .icon,.modal-menu a,.footer-menu a, .footer-widgets a,#site-footer .wp-block-button.is-style-outline,.wp-block-pullquote:before,.singular:not(.overlay-header) .entry-header a,.archive-header a,.header-footer-group .color-accent,.header-footer-group .color-accent-hover:hover { color: #cd2653; }.social-icons a,#site-footer button:not(.toggle),#site-footer .button,#site-footer .faux-button,#site-footer .wp-block-button__link,#site-footer .wp-block-file__button,#site-footer input[type=\"button\"],#site-footer input[type=\"reset\"],#site-footer input[type=\"submit\"] { background-color: #cd2653; }.header-footer-group,body:not(.overlay-header) #site-header .toggle,.menu-modal .toggle { color: #000000; }body:not(.overlay-header) .primary-menu ul { background-color: #000000; }body:not(.overlay-header) .primary-menu > li > ul:after { border-bottom-color: #000000; }body:not(.overlay-header) .primary-menu ul ul:after { border-left-color: #000000; }.site-description,body:not(.overlay-header) .toggle-inner .toggle-text,.widget .post-date,.widget .rss-date,.widget_archive li,.widget_categories li,.widget cite,.widget_pages li,.widget_meta li,.widget_nav_menu li,.powered-by-wordpress,.to-the-top,.singular .entry-header .post-meta,.singular:not(.overlay-header) .entry-header .post-meta a { color: #6d6d6d; }.header-footer-group pre,.header-footer-group fieldset,.header-footer-group input,.header-footer-group textarea,.header-footer-group table,.header-footer-group table *,.footer-nav-widgets-wrapper,#site-footer,.menu-modal nav *,.footer-widgets-outer-wrapper,.footer-top { border-color: #dcd7ca; }.header-footer-group table caption,body:not(.overlay-header) .header-inner .toggle-wrapper::before { background-color: #dcd7ca; }\n<\/style>\n<link rel='stylesheet' id='wpweb-print-style-css' href='https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/themes\/wpweb\/print.css?ver=1.0.0' media='print' \/>\n<link rel='stylesheet' id='vcv:assets:front:style-css' href='https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/plugins\/visualcomposer\/public\/dist\/front.bundle.css?ver=45.8.0' media='all' \/>\n<link rel='stylesheet' id='vcv:assets:source:styles:assetslibrarybackgroundsimpledistbackgroundsimplebundlecss-css' href='https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/plugins\/visualcomposer\/public\/sources\/assetsLibrary\/backgroundSimple\/dist\/backgroundSimple.bundle.css?ver=45.8.0-2185' media='all' \/>\n<style id='vcv-globalElementsCss-inline-css'>\n.ce-navigation-left h4{color:#2a4a73;font-size:20px;line-height:24px}.ce-navigation-left p{color:#000}.ce-navigation-left a,.ce-navigation-left p{font-size:16px;font-weight:300;line-height:28px}.ce-navigation-left a{color:#2a4a73;text-decoration:none}.ce-navigation-left ul{list-style:none;margin:0;padding:0}.ce-navigation-left li{margin:0}.ce-navigation-left li a{border-bottom:1px solid #eee;color:#2a4a73;display:block;font-size:16px;font-weight:300;line-height:28px;list-style:none;margin:0;padding-bottom:5px;padding-left:20px;padding-top:5px;position:relative;text-decoration:none;transition:all .5s ease-in-out}.ce-navigation-left li a:before{border-color:transparent transparent transparent #2a4a73;border-style:solid;border-width:5px 0 5px 6px;content:\"\";height:0;left:0;position:absolute;top:13px;-webkit-transform:rotate(1turn);width:0}.ce-navigation-left li strong a{font-weight:700}.default-ce-text-block-wrapper h2{color:#2e849b;font-size:32px}.default-ce-text-block-wrapper h5{color:#2a4b74;font-size:25px}.default-ce-text-block-wrapper p{font-size:16px;font-weight:300;line-height:28px;margin-bottom:20px}.default-ce-text-block-wrapper a{color:#2a4a73;font-size:16px;font-weight:300;line-height:28px;text-decoration:none}.default-ce-text-block-wrapper ul{list-style:none;margin:0;padding:0}.default-ce-text-block-wrapper li{font-size:16px;font-weight:300;line-height:28px;margin-left:0;padding-left:20px;position:relative}.default-ce-text-block-wrapper li:before{background:#2a4b74;content:\"\";height:10px;left:0;position:absolute;top:8px;width:10px}@media (max-width:600px){#flip-box-wrapper .vce-flip-box-front{background-color:#1a2543;background-repeat:no-repeat;background-size:contain}}\n<\/style>\n<!--vcv no format--><div class=\"vce-row-container\"><div class=\"vce-row vce-element--has-background vce-row--col-gap-30 newsletter-form-main-wrap  vce-row-columns--top vce-row-content--top\" data-vce-full-width=\"true\" id=\"el-13d8318d\" data-vce-do-apply=\"all el-13d8318d\"><div class=\"vce-content-background-container\"><div class=\"vce-asset-background-simple-container vce-visible-all-only vce-asset-background-simple--style-cover vce-asset-background-simple--position-center-center\"><div class=\"vce-asset-background-simple\"><div class=\"vce-asset-background-simple-item\" style=\"background-image: url('https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/wp-content\/uploads\/2021\/01\/form-bg.png');\"><\/div><\/div><\/div><\/div><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first good-reason-listing-item\" id=\"el-1c05522e\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-1c05522e\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-1c05522e\"><div class=\"vce-raw-html\"><div class=\"vce-raw-html-wrapper\" id=\"el-a5050a92\" data-vce-do-apply=\"all el-a5050a92\"><div class=\"comman-title-sites-wrapper newsletter-form-heading text-bg-white-custom-text\"> <div class=\"comman-title-sites-title\"> <h2><div>Sign up for our newsletter and get the online edition of 'Die Mediation' Q1-2020 free.<\/div><\/h2><\/div><\/div><\/div><\/div><div class=\"vce-row-container\"><div class=\"vce-row vce-row--col-gap-30 vce-row-columns--top vce-row-content--top\" id=\"el-f6684f81\" data-vce-do-apply=\"all el-f6684f81\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-100p vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-c33eb535\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-c33eb535\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-c33eb535\"><div id=\"el-38e450e4\" class=\"vce-contact-form-7--align-left\"><div class=\"vce vce-contact-form-7\" data-vce-do-apply=\"all el-38e450e4\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f2223-o1\" lang=\"de-DE\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/2228#wpcf7-f2223-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Kontaktformular\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"2223\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.9.4\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_DE\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2223-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_uacf7_hidden_conditional_fields\" value=\"\" \/>\n<\/div>\n<div class=\"uacf7-form-2223\"><div class=\"registraniotn-form\">\n   <div class=\"registraniotn-form-input\">\n      <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n   <\/div>\n   <div class=\"registraniotn-form-input\">\n      <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail address\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n   <\/div>\n   <div class=\"registraniotn-form-button\"><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" id=\"send\" type=\"submit\" value=\"SEND\" \/><\/div>\n<\/div><\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"185\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><!--vcv no format--><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;Die Mediation&#8217;In our quarterly magazine, we deal with mediation and much more. Discover new topics full of in-depth and multi-faceted articles by experts in mediation, law and social sciences. Read about the latest trends in recurring topics such as conflict resoltuion, change management, leadership, best market practices, and cross-cultural travel. Buy your German copy and [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":2397,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-full-width.php","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"_links":{"self":[{"href":"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/en\/wp-json\/wp\/v2\/pages\/2228"}],"collection":[{"href":"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/en\/wp-json\/wp\/v2\/comments?post=2228"}],"version-history":[{"count":16,"href":"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/en\/wp-json\/wp\/v2\/pages\/2228\/revisions"}],"predecessor-version":[{"id":6116,"href":"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/en\/wp-json\/wp\/v2\/pages\/2228\/revisions\/6116"}],"up":[{"embeddable":true,"href":"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/en\/wp-json\/wp\/v2\/pages\/2397"}],"wp:attachment":[{"href":"https:\/\/steinbeis-mediation-t3.tender-shockley.212-132-97-211.plesk.page\/en\/wp-json\/wp\/v2\/media?parent=2228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}